{"id":2463,"date":"2023-05-02T17:39:17","date_gmt":"2023-05-02T17:39:17","guid":{"rendered":"https:\/\/blog.archipad.com\/?p=2463"},"modified":"2023-09-21T16:48:20","modified_gmt":"2023-09-21T16:48:20","slug":"etude-de-cas-archipad-et-lautomatisation-dune-synthese-hebdomadaire","status":"publish","type":"post","link":"https:\/\/archipad.com\/fr\/etude-de-cas-archipad-et-lautomatisation-dune-synthese-hebdomadaire\/","title":{"rendered":"\u00c9tude de cas : Archipad et l&rsquo;automatisation d&rsquo;une synth\u00e8se hebdomadaire"},"content":{"rendered":"\n<p>Les personnalisations d&rsquo;Archipad s&rsquo;ajustent aux besoins des sp\u00e9cificit\u00e9s m\u00e9tiers, r\u00e9pondent aux imp\u00e9ratifs des proc\u00e9dures de suivi de chantier propres \u00e0 chaque entreprise : de la d\u00e9finition du besoin aux b\u00e9n\u00e9fices utilisateur, Archipad collabore avec ses clients au plus pr\u00e8s de leurs m\u00e9tiers. Exemple avec les personnalisations r\u00e9alis\u00e9es pour Solares Bauen.<\/p>\n\n\n\n<p>Utilisatrices d\u2019Archipad depuis 2018, les huit \u00e9quipes de Solares Bauen, bureau d\u2019\u00e9tude fluides, thermique et environnement dans le b\u00e2timent, et leur responsable de suivi de chantier collaborent plus efficacement gr\u00e2ce \u00e0 une personnalisation d\u2019Archipad con\u00e7ue sp\u00e9cifiquement pour r\u00e9pondre \u00e0 leurs besoins.<\/p>\n\n\n\n<p>\u00ab Nous avons gagn\u00e9 en fluidit\u00e9 car nous pouvons anticiper davantage et r\u00e9duire drastiquement le risque d\u2019oubli. Au final, nous gagnons beaucoup de temps. \u00bb<\/p>\n\n\n\n<p><em>Julien Kauffmann, Responsable suivi de chantier Solares Bauen<\/em><\/p>\n\n\n\n<p><strong>Pr\u00e9sentation de Solares Bauen<br><\/strong><br>Cr\u00e9\u00e9 en 1999 \u00e0 Fribourg par d\u2019anciens chercheurs du Fraunhofer-Institut f\u00fcr Solare Energiesysteme, Solares Bauen est un bureau d\u2019\u00e9tude franco-allemand, bas\u00e9 \u00e0 Strasbourg, sp\u00e9cialis\u00e9 dans l\u2019utilisation rationnelle de l\u2019\u00e9nergie et dans celle des \u00e9nergies renouvelables dans le secteur du b\u00e2timent. Ses 70 ing\u00e9nieurs et techniciens, r\u00e9partis sur 5 agences en France et en Allemagne, r\u00e9pondent aux hautes exigences environnementales des ma\u00eetres d\u2019ouvrage en termes de r\u00e9duction des d\u00e9penses d\u2019\u00e9nergie, de production d\u2019\u00e9nergies renouvelables et de confort des habitants. Ils ont d\u00e9velopp\u00e9 une expertise pointue dans la conception de b\u00e2timents \u00e0 \u00e9nergie positive et passifs et dans les projets certifi\u00e9s HQE.<\/p>\n\n\n\n<p><strong>Leur besoin : faciliter la mutualisation et la planification de leurs suivis de chantier<br><\/strong><br>Comment organiser efficacement le suivi de chantier d\u2019une centaine de projets g\u00e9r\u00e9s par huit \u00e9quipes dispers\u00e9es g\u00e9ographiquement ? Telle \u00e9tait la probl\u00e9matique.<\/p>\n\n\n\n<p>Le responsable de suivi de chantier de Solares Bauen a pour mission de d\u00e9charger au maximum les \u00e9quipes projets du suivi de chantier en v\u00e9rifiant l\u2019ex\u00e9cution des proc\u00e9dures de suivi, organisant et planifiant le suivi de l\u2019ensemble des chantiers afin de garantir l\u2019exigence qualit\u00e9. Il fait le point sur l\u2019\u00e9tat d\u2019avancement des chantiers et planifie ses visites de chantier sur quinze jours deux fois par mois tout en mutualisant ses d\u00e9placements. Solares Bauen souhaitait donc disposer d&rsquo;un fichier r\u00e9capitulatif hebdomadaire de ses diff\u00e9rents projets en cours sur lequel s\u2019appuyer pour pr\u00e9parer ses r\u00e9unions d\u2019\u00e9quipe.<\/p>\n\n\n\n<p>\u00ab Nous avions besoin de trouver une solution pour faciliter la collecte des donn\u00e9es de nos chantiers et fluidifier la communication entre les huit \u00e9quipes projets et le responsable du suivi de chantier. Organiser un planning de suivi de l\u2019ensemble de nos chantiers, ce n\u2019est pas simple parce qu\u2019il faut \u00e0 la fois g\u00e9rer les urgences impr\u00e9vues et les visites r\u00e9guli\u00e8res. Par ailleurs, l\u2019objectif \u00e9tait \u00e9galement de pouvoir pr\u00e9voir et anticiper ma charge de travail sur quinze jours. \u00bb<\/p>\n\n\n\n<p><strong>La d\u00e9finition d\u2019une solution : l\u2019\u00e9coute client et la collaboration<br><\/strong><br>\u00ab Nous avons expliqu\u00e9 notre situation \u00e0 Archipad et nous avons beaucoup \u00e9chang\u00e9 avec le Product Owner afin de clarifier et affiner notre besoin. Cette collaboration a permis \u00e0 l\u2019\u00e9quipe d\u2019Archipad d\u2019aboutir \u00e0 une solution d\u2019extraction des donn\u00e9es collect\u00e9es sur l\u2019ensemble de nos projets, puis d\u2019organisation sous la forme d\u2019un tableau Excel simple \u00e0 lire. \u00bb<\/p>\n\n\n\n<p><strong>La mise en place et l\u2019ex\u00e9cution de la solution<br><\/strong><br>De nouveaux champs personnalis\u00e9s ont \u00e9t\u00e9 cr\u00e9\u00e9s dans l&rsquo;application : niveaux de criticit\u00e9, phases de travaux, date des visites\u2026<\/p>\n\n\n\n<p>La programmation de scripts permet de r\u00e9cup\u00e9rer les donn\u00e9es et de les exporter automatiquement.<br>Le client re\u00e7oit un export des informations contenues dans Archipad sous la forme d\u2019un document contenant un tableau r\u00e9capitulatif des projets en cours avec les informations suivantes : r\u00e9f\u00e9rence interne du projet, nom du projet, adresse du chantier, nom du responsable du suivi de chantier, date de la derni\u00e8re visite de suivi de chantier, date de la premi\u00e8re visite, nom de la phase en cours, nombre de visites r\u00e9alis\u00e9es, cr\u00e9neau r\u00e9current de la visite de suivi de chantier, nombre de jours restant jusqu&rsquo;\u00e0 la prochaine visite pr\u00e9vue&#8230; Des codes couleur simplifient la lecture des informations.<\/p>\n\n\n\n<p>Le document est disponible au format PDF pour b\u00e9n\u00e9ficier d&rsquo;une mise en page propre mais \u00e9galement au format Excel pour pourvoir filtrer les donn\u00e9es (par code postal par exemple) et les faire parler ainsi plus simplement.<br>Le script s&rsquo;ex\u00e9cute sur les serveurs tous les dimanches et envoie automatiquement les documents g\u00e9n\u00e9r\u00e9s \u00e0 temps pour la r\u00e9union du lundi.<\/p>\n\n\n\n<p>\u00ab Le service technique d\u2019Archipad est tr\u00e8s performant. Je remonte en permanence les remarques de nos \u00e9quipes pour des am\u00e9liorations possibles. Nous avons toujours le bon interlocuteur au bon moment. Nous avons vraiment l\u2019impression d\u2019\u00eatre \u00e9cout\u00e9s. Ce que nous disons est pris en compte, puis impl\u00e9ment\u00e9s si nos retours sont justifi\u00e9s. \u00bb<\/p>\n\n\n\n<p>L&rsquo;objectif des personnalisations Archipad est d&rsquo;apporter toujours plus de fluidit\u00e9, de simplicit\u00e9 dans le suivi de chantier. Parce qu&rsquo;elles permettent \u00e0 chaque entreprise d&rsquo;adapter Archipad \u00e0 ses besoins, elles sont synonymes \u00e0 la fois de qualit\u00e9 et de productivit\u00e9. Fruits d&rsquo;une collaboration \u00e9troite entre Archipad et vos \u00e9quipes sur le terrain, elles sont con\u00e7ues dans un esprit d&rsquo;optimisation constante. De la d\u00e9finition de votre besoin \u00e0 l&rsquo;application pratique dans vos suivis de chantier, les \u00e9quipes d&rsquo;Archipad vous accompagnent pas \u00e0 pas.<\/p>\n\n\n\n<p><em>Photographie : (c) DR<br><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les personnalisations d&rsquo;Archipad s&rsquo;ajustent aux besoins des sp\u00e9cificit\u00e9s m\u00e9tiers, r\u00e9pondent aux imp\u00e9ratifs des proc\u00e9dures de suivi de chantier propres \u00e0 chaque entreprise : de la d\u00e9finition du besoin aux b\u00e9n\u00e9fices utilisateur, Archipad collabore avec ses clients au plus pr\u00e8s de leurs m\u00e9tiers. Exemple avec les personnalisations r\u00e9alis\u00e9es pour Solares Bauen. Utilisatrices d\u2019Archipad depuis 2018, les [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2744,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"categories":[220],"tags":[311,209,312,277,208],"class_list":["post-2463","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-etude-de-cas","tag-application-de-suivi-de-chantier","tag-archipad","tag-logiciel-de-suivi-de-chantier","tag-personnalisation","tag-suivi-de-chantier"],"_links":{"self":[{"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/posts\/2463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/comments?post=2463"}],"version-history":[{"count":0,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/posts\/2463\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/media\/2744"}],"wp:attachment":[{"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/media?parent=2463"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/categories?post=2463"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/tags?post=2463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}