{"id":2324,"date":"2022-05-23T10:45:40","date_gmt":"2022-05-23T08:45:40","guid":{"rendered":"https:\/\/blog.archipad.com\/?p=2324"},"modified":"2023-09-21T16:28:48","modified_gmt":"2023-09-21T16:28:48","slug":"la-maitrise-du-suivi-de-chantier-la-gestion-et-supervision-du-circuit-des-visas","status":"publish","type":"post","link":"https:\/\/archipad.com\/fr\/la-maitrise-du-suivi-de-chantier-la-gestion-et-supervision-du-circuit-des-visas\/","title":{"rendered":"La ma\u00eetrise du suivi de chantier : la gestion et supervision du circuit des visas"},"content":{"rendered":"<p style=\"text-align: left;\">\u00c9tape de v\u00e9rification cruciale pour la ma\u00eetrise des risques, le circuit des visas est le passage oblig\u00e9 de contr\u00f4le par la ma\u00eetrise d\u2019\u0153uvre des plans d\u2019ex\u00e9cution r\u00e9alis\u00e9s par les diff\u00e9rents corps d\u2019\u00e9tat pr\u00e9sents sur un chantier. Les visas assurent la bonne conformit\u00e9 et la coh\u00e9rence des plans d\u2019ex\u00e9cution par rapport \u00e0 l\u2019\u00e9tude de conception du projet.<\/p>\n<p style=\"text-align: left;\">Anticiper, pr\u00e9parer, organiser, planifier, coordonner, sont autant de verbes d\u00e9terminants pour la r\u00e9ussite d\u2019un projet. Les chantiers de construction ou de r\u00e9novation mobilisent de nombreux corps d\u2019\u00e9tat dont les interventions doivent \u00eatre coordonn\u00e9es dans le temps et dans l\u2019espace, d\u2019autant plus que l\u2019ex\u00e9cution des travaux implique des contraintes et des obligations techniques, administratives et financi\u00e8res pour chacun des intervenants. La phase de pr\u00e9paration est donc capitale : les \u00e9tudes d&rsquo;ex\u00e9cution et plans d&rsquo;ex\u00e9cution sont ces outils fondamentaux qui permettent de planifier au mieux un projet de construction ou de r\u00e9habilitation.<\/p>\n<p style=\"text-align: left;\">La construction d\u2019un ouvrage, ou sa r\u00e9habilitation, d\u00e9pend en effet de la mise en \u0153uvre coh\u00e9rente des \u00e9tudes d\u2019ex\u00e9cution dont l\u2019objectif majeur est de planifier la r\u00e9alisation technique des projets, de d\u00e9finir la mani\u00e8re dont les entreprises vont intervenir pour mener \u00e0 bien le chantier.<\/p>\n<p style=\"text-align: left;\">L\u2019\u00e9tude d\u2019ex\u00e9cution men\u00e9e par la ma\u00eetrise d\u2019\u0153uvre est une \u00e9tude de d\u00e9finition qui permet au ma\u00eetre d\u2019ouvrage et aux entreprises de bien comprendre l\u2019ouvrage et \u00e0 l\u2019entreprise de chiffrer et de pr\u00e9parer son chantier. L\u2019\u00e9tude d\u2019ex\u00e9cution men\u00e9e par l\u2019entreprise ou les entreprises en charge du chantier est une \u00e9tude de r\u00e9alisation ou de fabrication ; elle est destin\u00e9e aux \u00e9quipes de montage et d\u2019ex\u00e9cution, c\u2019est \u00e0 dire aux salari\u00e9s des entreprises. Sa finalit\u00e9 est donc de<br \/>\npermettre la bonne compr\u00e9hension de l\u2019ouvrage \u00e0 construire dans les conditions r\u00e9elles du terrain et donc in fine de permettre sa r\u00e9alisation.<\/p>\n<p style=\"text-align: left;\">La qualit\u00e9 des \u00e9tudes d\u2019ex\u00e9cution des entreprises a un r\u00f4le majeur dans le d\u00e9roulement du chantier. Elles contribuent non seulement \u00e0 la s\u00e9curit\u00e9 des intervenants sur le chantier mais elles sont aussi et surtout le support de travail indispensable des professionnels du b\u00e2timent. Ses \u00e9tudes sont constitu\u00e9es des plans d\u2019ex\u00e9cution, des fiches techniques sur les mat\u00e9riaux, marques, normes, types de mise en \u0153uvre, des notes de calculs, des \u00e9chantillons, de certificats divers, etc. Chacun de ces documents est contr\u00f4l\u00e9 par le ma\u00eetre d\u2019\u0153uvre qui y appose un avis : le visa de l\u2019\u00e9tude d\u2019ex\u00e9cution.<\/p>\n<p style=\"text-align: left;\"><strong>La forme ou d\u00e9nomination des visas d\u2019ex\u00e9cution : leurs cons\u00e9quences<br \/>\n<\/strong><br \/>\nBien qu\u2019aucun texte n\u2019encadre la forme des visas, trois formules sont g\u00e9n\u00e9ralement utilis\u00e9es :<\/p>\n<p>\u2022 Sans observation : les documents sont valid\u00e9s et \u00ab bon pour ex\u00e9cution \u00bb sur le terrain<br \/>\n\u2022 Avec observations : l\u2019entreprise est oblig\u00e9e d\u2019apporter des modifications<br \/>\n\u2022 A resoumettre ou refus\u00e9 : les travaux ne peuvent \u00eatre r\u00e9alis\u00e9s sans un nouvel avis<\/p>\n<p>Concr\u00e8tement, mieux vaut pour une entreprise un visa de refus sur une fiche technique de lavabo que de d\u00e9monter un lavabo d\u00e9j\u00e0 pos\u00e9, car le document vis\u00e9 est bien in fine le support de travail de l\u2019ouvrier sur le terrain.<\/p>\n<p>Les documents vis\u00e9s avec ou sans observations autorisent l\u2019entreprise \u00e0 r\u00e9aliser la prestation et donc \u00e0 commander les fournitures, ce qu\u2019elle ne doit pas faire avant l\u2019obtention de ces visas.<\/p>\n<p><strong>NB<\/strong> : Le ma\u00eetre d\u2019\u0153uvre n\u2019a pas \u00e0 attendre les avis du bureau de contr\u00f4le, c\u2019est l\u2019entreprise qui doit attendre cet avis avant de r\u00e9aliser les travaux. Certains ma\u00eetres d\u2019\u0153uvre indiquent donc dans les visas \u00ab sous r\u00e9serve de l\u2019avis du bureau de contr\u00f4les \u00bb quand le recours \u00e0 celui-ci est obligatoire. (Le code de la construction et de l\u2019habitation pr\u00e9voit l\u2019obligation de contr\u00f4le technique pour certains b\u00e2timents. La loi encadrant cette obligation est la loi Spinetta n\u00b078-<br \/>\n12 du 4 janvier 1978).<\/p>\n<p style=\"text-align: left;\"><strong>La mise en coh\u00e9rence technique des documents fournis par les entreprises : le circuit des <\/strong><strong>visas<br \/>\n<\/strong><br \/>\nLa mise en coh\u00e9rence de tous les documents d\u2019ex\u00e9cution passe par une synth\u00e8se de tous les \u00e9l\u00e9ments de la construction afin de s\u2019assurer de leur coh\u00e9rence et de leur mise en \u0153uvre dans le respect du projet architectural.<\/p>\n<p style=\"text-align: left;\">Le circuit des visas est rappel\u00e9 lors de la r\u00e9union de lancement de chantier. L\u2019ensemble des documents peuvent alors faire l\u2019objet de remarques de la part des diff\u00e9rents corps d\u2019\u00e9tat. Pour \u00e9viter toute redondance ou contradiction, une relecture et une synth\u00e8se sont n\u00e9cessaires avant la diffusion aux diff\u00e9rentes entreprises. La synth\u00e8se est pilot\u00e9e et valid\u00e9e par le responsable de la coh\u00e9rence du projet : l\u2019architecte.<\/p>\n<p style=\"text-align: left;\"><strong>Les armoires \u00e0 plans : la solution pour assurer le bon d\u00e9roulement du circuit des visas<\/p>\n<p><\/strong>La mise en place d\u2019une armoire \u00e0 plans informatis\u00e9e int\u00e9grant des fonctionnalit\u00e9s de gestion \u00e9lectronique des documents (GED) assure la fluidit\u00e9 et le bon d\u00e9roulement du circuit des visas. L\u2019utilisateur peut visualiser les documents d\u2019ex\u00e9cution en PDF auxquels est rattach\u00e9 un visa. Les pr\u00e9c\u00e9dentes versions des documents sont automatiquement archiv\u00e9es. L\u2019architecte peut relire, compl\u00e9ter et valider les observations des bureaux d\u2019\u00e9tudes techniques (BET) int\u00e9gr\u00e9s \u00e0 l\u2019\u00e9quipe de ma\u00eetrise d\u2019\u0153uvre, observations qui ne seront visibles par les entreprises qu\u2019apr\u00e8s validation. En fin de chantier, tout est conserv\u00e9 pour archivage.<\/p>\n<p style=\"text-align: left;\">La r\u00e9alisation des documents d\u2019ex\u00e9cution et leur mise en coh\u00e9rence ont beaucoup b\u00e9n\u00e9fici\u00e9 de l\u2019avanc\u00e9e technologique du BIM. La maquette 3D sur laquelle tous les intervenants collaborent a nettement am\u00e9lior\u00e9 la visibilit\u00e9 du projet pour l\u2019ensemble des corps d\u2019\u00e9tat. De la m\u00eame mani\u00e8re, cette nouvelle tra\u00e7abilit\u00e9 que permet la technologie r\u00e9duit consid\u00e9rablement le risque d\u2019erreurs ou de d\u00e9faillances en cours de chantier puisque tous les intervenants sont inform\u00e9s en temps r\u00e9el des observations \u00e9mises et des documents diffus\u00e9s : un r\u00e9el gain d\u2019efficacit\u00e9 pour tous.<\/p>\n<p style=\"text-align: left;\"><em>Photographie : (c) Nuei57<br \/>\n<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9tape de v\u00e9rification cruciale pour la ma\u00eetrise des risques, le circuit des visas est le passage oblig\u00e9 de contr\u00f4le par la ma\u00eetrise d\u2019\u0153uvre des plans d\u2019ex\u00e9cution r\u00e9alis\u00e9s par les diff\u00e9rents corps d\u2019\u00e9tat pr\u00e9sents sur un chantier. Les visas assurent la bonne conformit\u00e9 et la coh\u00e9rence des plans d\u2019ex\u00e9cution par rapport \u00e0 l\u2019\u00e9tude de conception du [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":2328,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":"","footnotes":""},"categories":[178],"tags":[209,288,208,291],"class_list":["post-2324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-conseils-astuces","tag-archipad","tag-ged","tag-suivi-de-chantier","tag-visas"],"_links":{"self":[{"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/posts\/2324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/comments?post=2324"}],"version-history":[{"count":0,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/posts\/2324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/media\/2328"}],"wp:attachment":[{"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/media?parent=2324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/categories?post=2324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/archipad.com\/fr\/wp-json\/wp\/v2\/tags?post=2324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}